{"id":3,"date":"2023-09-20T13:47:31","date_gmt":"2023-09-20T13:47:31","guid":{"rendered":"https:\/\/createc.es\/?page_id=3"},"modified":"2023-10-04T06:43:57","modified_gmt":"2023-10-04T06:43:57","slug":"politica-privacidad","status":"publish","type":"page","link":"https:\/\/createc.es\/en\/politica-privacidad\/","title":{"rendered":"Pol\u00edtica Privacidad"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27373cd9 e-flex e-con-boxed e-con e-parent\" data-id=\"27373cd9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28b15c00 elementor-widget elementor-widget-text-editor\" data-id=\"28b15c00\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 14-09-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div id=\"main-content\">\n<div class=\"container\">\n<div id=\"content-area\" class=\"clearfix\">\n<div id=\"left-area\">\n<article id=\"post-1260\" class=\"post-1260 page type-page status-publish hentry\">\n<h1 class=\"entry-title main_title\">Privacy Policy<\/h1>\n<div class=\"entry-content\">\n<p class=\"p1\"><b>Informaci\u00f3n en cumplimiento de la normativa de protecci\u00f3n de datos personales<\/b><\/p>\n<p class=\"p3\">En Europa y en Espa\u00f1a existen normas de protecci\u00f3n de datos pensadas para proteger su informaci\u00f3n personal de obligado cumplimiento para nuestra entidad.<\/p>\n<p class=\"p3\">Por ello, es muy importante para nosotros que entienda perfectamente qu\u00e9 vamos a hacer con los datos personales que le pedimos.<\/p>\n<p class=\"p3\">As\u00ed, seremos transparentes y le daremos el control de sus datos, con un lenguaje sencillo y opciones claras que le permitir\u00e1n decidir qu\u00e9 haremos con su informaci\u00f3n personal.<\/p>\n<p class=\"p3\">Por favor, si una vez le\u00edda la presente informaci\u00f3n le queda alguna duda, no dude en preguntarnos.<\/p>\n<p class=\"p3\">Muchas gracias por su colaboraci\u00f3n.<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>\u00bfQui\u00e9nes somos?<\/b><\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li5\">Nuestra denominaci\u00f3n: <b>CREATEC ROBOTIC AUTOMATION S.L<\/b><\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li5\">Nuestro CIF \/ NIF: <b>B02538064<\/b><\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li5\">Nuestra actividad principal:<b> SISTEMAS DE PROCESO AUTOMATICO PARA LA INDUSTRIA ALIMENTARIA<\/b><\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li5\">Nuestra direcci\u00f3n: <b>POLIGONO INDUSTRIAL CAMPOLLANO, 1\u00aa AVENIDA, N\u00ba 77, CP 02007, ALBACETE (Albacete)<\/b><\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li5\">Nuestro tel\u00e9fono de contacto: <b>967264763<\/b><\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li5\">Nuestra direcci\u00f3n de correo electr\u00f3nico de contacto: <b>administracion@createc.es<\/b><\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li5\">Nuestra p\u00e1gina web: <b>www.createc.es<\/b><\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li5\">Para su confianza y seguridad, le informamos que somos una entidad inscrita en el siguiente Registro Mercantil \/Registro P\u00fablico:<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li5\">Nuestra actividad principal est\u00e1 sujeta a un r\u00e9gimen de autorizaci\u00f3n administrativa previa. Para su confianza y seguridad, le facilitamos los datos relativos a dicha autorizaci\u00f3n y los identificativos del \u00f3rgano competente de nuestra supervisi\u00f3n:<\/li>\n<\/ul>\n<p class=\"p8\"><b>Autorizaci\u00f3n administrativa: <\/b><\/p>\n<p class=\"p8\"><b>\u00d3rgano encargado de nuestra supervisi\u00f3n:<\/b><\/p>\n<p class=\"p9\"><b>(EN CASO DE QUE LA ACTIVIDAD EST\u00c9 SUJETA A UN R\u00c9GIMEN DE AUTORIZACI\u00d3N ADMINISTRATIVA)<\/b><\/p>\n<ul class=\"ul1\">\n<li class=\"li5\">El responsable de esta p\u00e1gina web ejerce una profesi\u00f3n regulada, para lo cual le facilitamos la siguiente informaci\u00f3n:<\/li>\n<\/ul>\n<p class=\"p8\"><b>Colegio profesional al que pertenece: <\/b><\/p>\n<p class=\"p8\"><b>T\u00edtulo acad\u00e9mico oficial o profesional:<\/b><\/p>\n<p class=\"p8\"><b>Estado de la Uni\u00f3n Europea en que se expidi\u00f3 dicho t\u00edtulo:<\/b><\/p>\n<p class=\"p8\"><b>Normas profesionales aplicables al ejercicio de la profesi\u00f3n:<\/b><\/p>\n<p class=\"p9\"><b>(EN CASO DE QUE EL RESPONSABLE DE LA P\u00c1GINA WEB EJERZA UNA PROFESI\u00d3N REGULADA)<\/b><\/p>\n<p class=\"p11\">Estamos a su disposici\u00f3n, no dude en contactar con nosotros.<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>\u00bfPara qu\u00e9 vamos a usar sus datos?<\/b><\/li>\n<\/ul>\n<p class=\"p13\">Con car\u00e1cter general, sus datos personales ser\u00e1n usados para poder relacionarnos con usted y poder prestarle nuestros servicios.<\/p>\n<p class=\"p14\">Asimismo, tambi\u00e9n pueden ser usados para otras actividades, como enviarle publicidad o promocionar nuestras actividades.\u00a0<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>\u00bfPor qu\u00e9 necesitamos usar sus datos?<\/b><\/li>\n<\/ul>\n<p class=\"p13\">Sus datos personales son necesarios para poder relacionarnos con usted y poder prestarle nuestros servicios. En este sentido, pondremos a su disposici\u00f3n una serie de casillas que le permitir\u00e1n decidir de manera clara y sencilla sobre el uso de su informaci\u00f3n personal.\u00a0<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>\u00bfQui\u00e9n va a conocer la informaci\u00f3n que le pedimos?<\/b><\/li>\n<\/ul>\n<p class=\"p13\">Con car\u00e1cter general, s\u00f3lo el personal de nuestra entidad que est\u00e9 debidamente autorizado podr\u00e1 tener conocimiento de la informaci\u00f3n que le pedimos.<\/p>\n<p class=\"p13\">De igual modo, podr\u00e1n tener conocimiento de su informaci\u00f3n personal aquellas entidades que necesiten tener acceso a la misma para que podamos prestarle nuestros servicios. As\u00ed por ejemplo, nuestro banco conocer\u00e1 sus datos si el pago de nuestros servicios se realiza mediante tarjeta o transferencia bancaria.<\/p>\n<p class=\"p13\">Asimismo, tendr\u00e1n conocimiento de su informaci\u00f3n aquellas entidades p\u00fablicas o privadas a las cuales estemos obligados a facilitar sus datos personales con motivo del cumplimiento de alguna ley. Poni\u00e9ndole un ejemplo, la Ley Tributaria obliga a facilitar a la Agencia Tributaria determinada informaci\u00f3n sobre operaciones econ\u00f3micas que superen una determinada cantidad.<\/p>\n<p class=\"p11\">En el caso de que, al margen de los supuestos comentados, necesitemos dar a conocer<span class=\"Apple-converted-space\">\u00a0 <\/span>su informaci\u00f3n personal a otras entidades, le solicitaremos previamente su permiso a trav\u00e9s de opciones claras que le permitir\u00e1n decidir a este respecto.<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>\u00bfC\u00f3mo vamos a proteger sus datos?<\/b><\/li>\n<\/ul>\n<p class=\"p13\">Protegeremos sus datos con medidas de seguridad eficaces en funci\u00f3n de los riesgos que conlleve el uso de su informaci\u00f3n.<\/p>\n<p class=\"p11\">Para ello, nuestra entidad ha aprobado una Pol\u00edtica de Protecci\u00f3n de Datos y se realizan controles y auditor\u00edas anuales para verificar que sus datos personales est\u00e1n seguros en todo momento.<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>\u00bfEnviaremos sus datos a otros pa\u00edses?<\/b><\/li>\n<\/ul>\n<p class=\"p13\">En el mundo hay pa\u00edses que son seguros para sus datos y otros que no lo son tanto. As\u00ed por ejemplo, la Uni\u00f3n Europea es un entorno seguro para sus datos. Nuestra pol\u00edtica es no enviar su informaci\u00f3n personal a ning\u00fan pa\u00eds que no sea seguro desde el punto de vista de la protecci\u00f3n de sus datos.<\/p>\n<p class=\"p11\">En el caso de que, con motivo de prestarle el servicio, sea imprescindible enviar sus datos a un pa\u00eds que no sea tan seguro como Espa\u00f1a, siempre le solicitaremos previamente su permiso y aplicaremos medidas de seguridad eficaces que reduzcan los riesgos del env\u00edo de su informaci\u00f3n personal a otro pa\u00eds.<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>\u00bfDurante cu\u00e1nto tiempo vamos a conservar sus datos?<\/b><\/li>\n<\/ul>\n<p class=\"p11\">Conservaremos sus datos durante nuestra relaci\u00f3n y mientras nos obliguen las leyes. Una vez finalizados los plazos legales aplicables, procederemos a eliminarlos de forma segura y respetuosa con el medio ambiente.<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>\u00bfCu\u00e1les son sus derechos de protecci\u00f3n de datos?<\/b><\/li>\n<\/ul>\n<p class=\"p13\">En cualquier momento puede dirigirse a nosotros para saber qu\u00e9 informaci\u00f3n tenemos sobre usted, rectificarla si fuese incorrecta y eliminarla una vez finalizada nuestra relaci\u00f3n, en el caso de que ello sea legalmente posible.<\/p>\n<p class=\"p13\">Tambi\u00e9n tiene derecho a solicitar el traspaso de su informaci\u00f3n a otra entidad. Este derecho se llama \u201cportabilidad\u201d y puede ser \u00fatil en determinadas situaciones.<\/p>\n<p class=\"p13\">Para solicitar alguno de estos derechos, deber\u00e1 realizar una solicitud escrita a nuestra direcci\u00f3n, junto con una fotocopia de su DNI, para poder identificarle.<\/p>\n<p class=\"p13\">En las oficinas de nuestra entidad disponemos de formularios espec\u00edficos para solicitar dichos derechos y le ofrecemos nuestra ayuda para su cumplimentaci\u00f3n.<\/p>\n<p class=\"p11\">Para saber m\u00e1s sobre sus derechos de protecci\u00f3n de datos, puede consultar la<span class=\"Apple-converted-space\">\u00a0 <\/span>p\u00e1gina web de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (<a href=\"http:\/\/www.agpd.es\">www.agpd.es<\/a>).<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>\u00bfPuede retirar su consentimiento si cambia de opini\u00f3n en un momento posterior?<\/b><\/li>\n<\/ul>\n<p class=\"p13\">Usted puede retirar su consentimiento si cambia de opini\u00f3n sobre el uso de sus datos en cualquier momento.<\/p>\n<p class=\"p11\">As\u00ed por ejemplo, si usted en su d\u00eda estuvo interesado\/a en recibir publicidad de nuestros productos o servicios, pero ya no desea recibir m\u00e1s publicidad, puede hac\u00e9rnoslo constar a trav\u00e9s del formulario de oposici\u00f3n al tratamiento disponible en las oficinas de nuestra entidad.<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>En caso de que entienda que sus derechos han sido desatendidos, \u00bfd\u00f3nde puede formular una reclamaci\u00f3n?<\/b><\/li>\n<\/ul>\n<p class=\"p13\">En caso de que entienda que sus derechos han sido desatendidos por nuestra entidad, puede formular una reclamaci\u00f3n en la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, a trav\u00e9s de alguno de los medios siguientes:<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\">Sede electr\u00f3nica: www.agpd.es<\/li>\n<li class=\"li5\">Direcci\u00f3n postal: Agencia Espa\u00f1ola de Protecci\u00f3n de Datos C\/ Jorge Juan, 6 28001-Madrid<\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li5\">V\u00eda telef\u00f3nica: Telf. 901 100 099<span class=\"Apple-converted-space\"> \u00a0<\/span>Telf. 91 266 35 17<\/li>\n<\/ul>\n<p class=\"p11\">Formular una reclamaci\u00f3n en la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos no conlleva ning\u00fan coste y no es necesaria la asistencia de abogado ni procurador.<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>\u00bfElaboraremos perfiles sobre usted?<\/b><\/li>\n<\/ul>\n<p class=\"p13\">Nuestra pol\u00edtica es no elaborar perfiles sobre los usuarios de nuestros servicios.<\/p>\n<p class=\"p13\">No obstante, pueden existir situaciones en las que, con fines de prestaci\u00f3n del servicio, comerciales o de otro tipo, necesitemos elaborar perfiles de informaci\u00f3n sobre usted. Un ejemplo pudiera ser la utilizaci\u00f3n de su historial de compras o servicios para poder ofrecerle productos o servicios adaptados a sus gustos o necesidades.<\/p>\n<p class=\"p11\">En tal caso, aplicaremos medidas de seguridad eficaces que protejan su informaci\u00f3n en todo momento de personas no autorizadas que pretendan utilizarla en su propio beneficio.<\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><b>\u00bfUsaremos sus datos para otros fines?<\/b><\/li>\n<\/ul>\n<p class=\"p11\">Nuestra pol\u00edtica es no usar sus datos para otras finalidades distintas a las que le hemos explicado. Si, no obstante, necesit\u00e1semos usar sus datos para actividades distintas, siempre le solicitaremos previamente su permiso a trav\u00e9s de opciones claras que le permitir\u00e1n decidir al respecto.<\/p>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Privacidad Informaci\u00f3n en cumplimiento de la normativa de protecci\u00f3n de datos personales En Europa y en Espa\u00f1a existen normas de protecci\u00f3n de datos pensadas para proteger su informaci\u00f3n personal de obligado cumplimiento para nuestra entidad. Por ello, es muy importante para nosotros que entienda perfectamente qu\u00e9 vamos a hacer con los datos personales [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edtica Privacidad - createc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/createc.es\/en\/politica-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica Privacidad - createc\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de Privacidad Informaci\u00f3n en cumplimiento de la normativa de protecci\u00f3n de datos personales En Europa y en Espa\u00f1a existen normas de protecci\u00f3n de datos pensadas para proteger su informaci\u00f3n personal de obligado cumplimiento para nuestra entidad. Por ello, es muy importante para nosotros que entienda perfectamente qu\u00e9 vamos a hacer con los datos personales [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/createc.es\/en\/politica-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"createc\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-04T06:43:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/createc.es\/en\/politica-privacidad\/\",\"url\":\"https:\/\/createc.es\/en\/politica-privacidad\/\",\"name\":\"Pol\u00edtica Privacidad - createc\",\"isPartOf\":{\"@id\":\"https:\/\/createc.es\/en\/#website\"},\"datePublished\":\"2023-09-20T13:47:31+00:00\",\"dateModified\":\"2023-10-04T06:43:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/createc.es\/en\/politica-privacidad\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/createc.es\/en\/politica-privacidad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/createc.es\/en\/politica-privacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/createc.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica Privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/createc.es\/en\/#website\",\"url\":\"https:\/\/createc.es\/en\/\",\"name\":\"createc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/createc.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/createc.es\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/createc.es\/en\/#organization\",\"name\":\"createc\",\"url\":\"https:\/\/createc.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/createc.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/createc.es\/wp-content\/uploads\/2023\/09\/LogoAzulMarino_Mesa-de-trabajo-1.png\",\"contentUrl\":\"https:\/\/createc.es\/wp-content\/uploads\/2023\/09\/LogoAzulMarino_Mesa-de-trabajo-1.png\",\"width\":300,\"height\":100,\"caption\":\"createc\"},\"image\":{\"@id\":\"https:\/\/createc.es\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica Privacidad - createc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/createc.es\/en\/politica-privacidad\/","og_locale":"en_US","og_type":"article","og_title":"Pol\u00edtica Privacidad - createc","og_description":"Pol\u00edtica de Privacidad Informaci\u00f3n en cumplimiento de la normativa de protecci\u00f3n de datos personales En Europa y en Espa\u00f1a existen normas de protecci\u00f3n de datos pensadas para proteger su informaci\u00f3n personal de obligado cumplimiento para nuestra entidad. Por ello, es muy importante para nosotros que entienda perfectamente qu\u00e9 vamos a hacer con los datos personales [&hellip;]","og_url":"https:\/\/createc.es\/en\/politica-privacidad\/","og_site_name":"createc","article_modified_time":"2023-10-04T06:43:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/createc.es\/en\/politica-privacidad\/","url":"https:\/\/createc.es\/en\/politica-privacidad\/","name":"Pol\u00edtica Privacidad - createc","isPartOf":{"@id":"https:\/\/createc.es\/en\/#website"},"datePublished":"2023-09-20T13:47:31+00:00","dateModified":"2023-10-04T06:43:57+00:00","breadcrumb":{"@id":"https:\/\/createc.es\/en\/politica-privacidad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/createc.es\/en\/politica-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/createc.es\/en\/politica-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/createc.es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica Privacidad"}]},{"@type":"WebSite","@id":"https:\/\/createc.es\/en\/#website","url":"https:\/\/createc.es\/en\/","name":"createc","description":"","publisher":{"@id":"https:\/\/createc.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/createc.es\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/createc.es\/en\/#organization","name":"createc","url":"https:\/\/createc.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/createc.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/createc.es\/wp-content\/uploads\/2023\/09\/LogoAzulMarino_Mesa-de-trabajo-1.png","contentUrl":"https:\/\/createc.es\/wp-content\/uploads\/2023\/09\/LogoAzulMarino_Mesa-de-trabajo-1.png","width":300,"height":100,"caption":"createc"},"image":{"@id":"https:\/\/createc.es\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/createc.es\/en\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/createc.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/createc.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/createc.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/createc.es\/en\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":22,"href":"https:\/\/createc.es\/en\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":1941,"href":"https:\/\/createc.es\/en\/wp-json\/wp\/v2\/pages\/3\/revisions\/1941"}],"wp:attachment":[{"href":"https:\/\/createc.es\/en\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}